{"id":74167,"date":"2025-09-03T15:51:44","date_gmt":"2025-09-03T15:51:44","guid":{"rendered":"https:\/\/www.realvnc.com\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/"},"modified":"2025-09-03T15:51:44","modified_gmt":"2025-09-03T15:51:44","slug":"violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance","status":"publish","type":"blog","link":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/","title":{"rendered":"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance"},"content":{"rendered":"<h2 data-pm-slice=\"1 1 []\">La br\u00e8ve histoire de la violation de donn\u00e9es GoTo\/LastPass<\/h2>\n<p>GoTo a r\u00e9cemment annonc\u00e9 que, selon leur enqu\u00eate, \u00ab\u00a0un acteur de la menace a exfiltr\u00e9 des sauvegardes crypt\u00e9es d&rsquo;un service de stockage en nuage tiers li\u00e9 aux produits suivants : Central, Pro, join.me, Hamachi et RemotelyAnywhere\u00a0\u00bb. Paddy Srinivasan, PDG de GoTo, a soulign\u00e9 les efforts d\u00e9ploy\u00e9s par l&rsquo;entreprise pour informer ses clients et assurer leur s\u00e9curit\u00e9 \u00e0 la suite de cet incident. <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\"><\/p>\n<p>Un acteur de la cybermenace a \u00e9galement extrait une cl\u00e9 de chiffrement pour un segment des donn\u00e9es de sauvegarde chiffr\u00e9es. Parmi les informations affect\u00e9es pourraient figurer \u00ab\u00a0les noms d&rsquo;utilisateur des comptes, les mots de passe sal\u00e9s et hach\u00e9s, une partie des param\u00e8tres d&rsquo;authentification multifactorielle (MFA), ainsi que certains param\u00e8tres de produits et des informations de licence\u00a0\u00bb. \u00c0 la suite de cette faille de s\u00e9curit\u00e9 de GoTo, ses produits ont fait l&rsquo;objet d&rsquo;un examen approfondi afin de garantir leur s\u00e9curit\u00e9 et leur fonctionnalit\u00e9 pendant cette p\u00e9riode.  <\/p>\n<p>Les syst\u00e8mes de production de GoTo n&rsquo;ont pas \u00e9t\u00e9 affect\u00e9s au-del\u00e0 de ce qui a \u00e9t\u00e9 annonc\u00e9 pr\u00e9c\u00e9demment.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/24576493-ab98-462a-911d-32babadd011c.jpeg\"><\/p>\n<p>La soci\u00e9t\u00e9 LastPass, propri\u00e9t\u00e9 de GoTo, a \u00e9galement annonc\u00e9 r\u00e9cemment qu&rsquo;un incident survenu en ao\u00fbt 2022 \u00e9tait plus grave que ce que l&rsquo;on pensait. Les donn\u00e9es concern\u00e9es comprenaient des bases de donn\u00e9es crypt\u00e9es de GoToMyPC. Apr\u00e8s avoir d\u00e9clar\u00e9 dans un premier temps qu&rsquo;aucune donn\u00e9e client n&rsquo;avait \u00e9t\u00e9 affect\u00e9e, <a class=\"css-1rn59kg\" href=\"https:\/\/blog.lastpass.com\/2022\/12\/notice-of-recent-security-incident\/\" target=\"_blank\" rel=\"noopener noreferrer\">LastPass a admis en d\u00e9cembre que des donn\u00e9es client avaient \u00e9t\u00e9 compromises<\/a>. La partie non autoris\u00e9e avait acc\u00e9d\u00e9 \u00e0 un service de stockage en nuage tiers o\u00f9 LastPass stockait des donn\u00e9es, y compris des noms d&rsquo;utilisateur de compte, des mots de passe sal\u00e9s et hach\u00e9s. Les donn\u00e9es des clients concern\u00e9s peuvent contenir des noms d&rsquo;utilisateur et d&rsquo;autres informations sensibles.    <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cdn.pixabay.com\/photo\/2017\/02\/16\/08\/47\/castle-2070777_1280.jpg\" alt=\"\"><\/p>\n<p>L&rsquo;incident a \u00e9galement eu un impact sur les param\u00e8tres d&rsquo;authentification multi-facteurs (MFA) d&rsquo;un petit groupe de clients, en particulier en ce qui concerne les bases de donn\u00e9es crypt\u00e9es de Rescue et GoToMyPC. \u00c0 la suite de cet incident, GoTo a pris des mesures importantes pour prot\u00e9ger les mots de passe des comptes et renforcer ses mesures de s\u00e9curit\u00e9 globales. Une partie de ces mesures a consist\u00e9 \u00e0 contacter directement les clients concern\u00e9s pour les rassurer sur les sauvegardes crypt\u00e9es et l&rsquo;authentification plus robuste.  <\/p>\n<p>\u00c0 la suite de plusieurs failles de s\u00e9curit\u00e9, <a href=\"https:\/\/www.silicon.co.uk\/security\/cyberwar\/lastpass-separates-from-parent-after-security-incidents-561688\" target=\"_blank\" rel=\"noopener noreferrer\">LastPass s&rsquo;est officiellement s\u00e9par\u00e9e de GoTo<\/a> en mai 2024 pour se concentrer davantage sur la cybers\u00e9curit\u00e9. Cela lui a permis de prot\u00e9ger les donn\u00e9es de ses clients gr\u00e2ce \u00e0 sa plateforme de gestion d&rsquo;identit\u00e9 am\u00e9lior\u00e9e, garantissant ainsi que les mots de passe ne seront plus jamais viol\u00e9s. <\/p>\n<h2>Que vous apprend la faille de s\u00e9curit\u00e9 de GoTo sur la s\u00e9curit\u00e9 des donn\u00e9es ?<\/h2>\n<p>Il y a une chose essentielle \u00e0 retenir de tout ce qui pr\u00e9c\u00e8de : lorsque la s\u00e9curit\u00e9 n&rsquo;est pas la priorit\u00e9, ce sont les utilisateurs concern\u00e9s qui finissent par en souffrir. La confiance num\u00e9rique et la s\u00e9curit\u00e9 des donn\u00e9es sont essentielles pour nous, ici \u00e0 RealVNC. Nous pensons que tout fournisseur d&rsquo;<a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/discover\/remote-access\/\" target=\"_blank\" rel=\"noopener noreferrer\">acc\u00e8s \u00e0 distance<\/a>, en particulier un fournisseur de logiciels, devrait les prendre tr\u00e8s au s\u00e9rieux. En r\u00e9alit\u00e9, de nombreuses entreprises ne joignent pas le geste \u00e0 la parole en mati\u00e8re de s\u00e9curit\u00e9 suppl\u00e9mentaire. La <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/importance-digital-trust-software-provider\/\" target=\"_blank\" rel=\"noopener noreferrer\">confiance num\u00e9rique<\/a> et la s\u00e9curit\u00e9 des donn\u00e9es sont essentielles pour nous, chez RealVNC.   <\/p>\n<p>Nous construisons notre produit en pla\u00e7ant la <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/connect\/security\/\" target=\"_blank\" rel=\"noopener noreferrer\">s\u00e9curit\u00e9 au premier plan<\/a>, en adh\u00e9rant \u00e0 nos quatre principes de s\u00e9curit\u00e9 :<\/p>\n<ol>\n<li>Vous n&rsquo;avez pas besoin de faire confiance \u00e0 RealVNC en tant que soci\u00e9t\u00e9 pour faire confiance \u00e0 nos logiciels et services.<\/li>\n<li>Nous n&rsquo;enregistrons pas vos sessions et les donn\u00e9es ne peuvent pas \u00eatre d\u00e9crypt\u00e9es maintenant ou \u00e0 l&rsquo;avenir.<\/li>\n<li>Chaque connexion est trait\u00e9e comme si elle \u00e9tait effectu\u00e9e dans un environnement hostile.<\/li>\n<li>C&rsquo;est le propri\u00e9taire de l&rsquo;ordinateur distant qui d\u00e9cide en dernier ressort qui peut se connecter<\/li>\n<\/ol>\n<p>Chaque connexion est crypt\u00e9e de bout en bout \u00e0 un niveau allant jusqu&rsquo;\u00e0 256 bits AES. Nous disposons \u00e9galement d&rsquo;un syst\u00e8me <a class=\"css-1rn59kg\" href=\"https:\/\/help.realvnc.com\/hc\/en-us\/articles\/360002250077\" target=\"_blank\" rel=\"noopener noreferrer\">d&rsquo;authentification \u00e0 deux facteurs (2FA<\/a>) et nous vous recommandons vivement de l&rsquo;utiliser. <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/03\/security-logos-circle.png\" alt=\"Logos de s\u00e9curit\u00e9 et de conformit\u00e9 RealVNC\"><\/p>\n<h2>RealVNC Connect peut prouver qu&rsquo;il est s\u00e9curis\u00e9<\/h2>\n<p>Nous ne nous contentons pas d&rsquo;affirmer que nous sommes s\u00fbrs. Notre <a href=\"https:\/\/www.realvnc.com\/en\/discover\/remote-desktop\/?lai_vid=OXgx5neBnClaw&amp;lai_sr=60-64&amp;lai_sl=h\" target=\"_blank\" rel=\"noopener noreferrer\">solution d&rsquo;acc\u00e8s \u00e0 distance<\/a> est la seule \u00e0 avoir \u00e9t\u00e9 audit\u00e9e par un expert ind\u00e9pendant en s\u00e9curit\u00e9 et \u00e0 avoir re\u00e7u le feu vert. En effet, nous avons ouvert nos portes \u00e0 un <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/cure53-security-audit-reaffirms-realvnc-strong-security-stance\/\" target=\"_blank\" rel=\"noopener noreferrer\">audit de s\u00e9curit\u00e9 complet par Cure53<\/a>. Il s&rsquo;agit d&rsquo;un examen de s\u00e9curit\u00e9 beaucoup plus approfondi que le traditionnel test de p\u00e9n\u00e9tration annuel, les auditeurs b\u00e9n\u00e9ficiant d&rsquo;un acc\u00e8s complet \u00e0 notre code source, \u00e0 la documentation interne de l&rsquo;API et d&rsquo;une ligne de communication directe avec les d\u00e9veloppeurs. Nous sommes tr\u00e8s fiers des r\u00e9sultats, aucun probl\u00e8me critique n&rsquo;ayant \u00e9t\u00e9 d\u00e9tect\u00e9, ce qui ne fait que r\u00e9affirmer la solidit\u00e9 de notre position en mati\u00e8re de s\u00e9curit\u00e9. Nous continuerons \u00e0 travailler dur pour maintenir les m\u00eames normes de s\u00e9curit\u00e9 \u00e9lev\u00e9es.     <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/04\/unauthorized-access.jpg\"><\/p>\n<p>Nous sommes \u00e9galement heureux d&rsquo;annoncer que la version Android de RealVNC Server for Mobile est la <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/vnc-server-mobile-app-masa-validation\/\" target=\"_blank\" rel=\"noopener noreferrer\">premi\u00e8re application d&rsquo;acc\u00e8s \u00e0 distance <\/a>\u00e0 passer avec succ\u00e8s le processus MASA. Nous avons entrepris le processus pour notre application RealVNC Mobile Server en novembre 2022, en collaboration avec NCC Group, un laboratoire MASA autoris\u00e9 et un acteur cl\u00e9 de l&rsquo;industrie de la s\u00e9curit\u00e9. Notre application a \u00e9t\u00e9 \u00e9valu\u00e9e avec brio et a obtenu un r\u00e9sultat exceptionnel : PASS dans chaque domaine d\u00e8s le premier essai.  <\/p>\n<p>RealVNC continuera \u00e0 d\u00e9fier l&rsquo;ensemble de l&rsquo;industrie de suivre la m\u00eame voie en fournissant une s\u00e9curit\u00e9 suppl\u00e9mentaire pour ses produits. Nous l&rsquo;avons fait lors de <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/came-for-ducks-stayed-for-talks-realvnc-infosecurity-europe-2022\/\" target=\"_blank\" rel=\"noopener noreferrer\">r\u00e9cents \u00e9v\u00e9nements sur la cybers\u00e9curit\u00e9<\/a> et nous continuerons \u00e0 le faire \u00e0 l&rsquo;avenir. <\/p>\n<blockquote><p>\u00ab\u00a0<em>Chez RealVNC, nous partons du principe qu&rsquo;aucune entreprise ne devrait jamais croire un vendeur sur parole lorsqu&rsquo;il affirme que son logiciel est s\u00e9curis\u00e9. C&rsquo;est pourquoi nous avons choisi de r\u00e9aliser un audit en bo\u00eete blanche avec une soci\u00e9t\u00e9 de conseil en s\u00e9curit\u00e9 tr\u00e8s r\u00e9put\u00e9e pour le prouver.\u00a0\u00bb<\/em><\/p>\n<p>&#8211; Andrew Woodhouse, RealVNC Chief Information Officer<\/p><\/blockquote>\n<h2>Que faire ensuite ?<\/h2>\n<p>V\u00e9rifiez si votre fournisseur de logiciels (et surtout d&rsquo;acc\u00e8s \u00e0 distance) peut vous apporter la preuve de sa s\u00e9curit\u00e9. Et ne vous contentez pas de le croire sur parole ! Demandez une preuve sous la forme d&rsquo;un audit de s\u00e9curit\u00e9 ind\u00e9pendant r\u00e9cent. Si ce n&rsquo;est pas le cas, il existe d&rsquo;autres solutions qui r\u00e9pondent \u00e0 vos exigences en mati\u00e8re de s\u00e9curit\u00e9.   <\/p>\n<p>RealVNC Connect garantit un <a href=\"https:\/\/www.realvnc.com\/en\/connect\/\" target=\"_blank\" rel=\"noopener noreferrer\">acc\u00e8s \u00e0 distance<\/a> s\u00e9curis\u00e9 et fiable pour tous. Il int\u00e8gre \u00e0 la fois le visualiseur et le serveur RealVNC dans une application de bureau unifi\u00e9e. Son <a href=\"https:\/\/www.realvnc.com\/en\/blog\/realvnc-connect-v8-redesigned\/\" target=\"_blank\" rel=\"noopener noreferrer\">interface conviviale<\/a> et ses fonctionnalit\u00e9s telles que le transfert de fichiers, la barre d&rsquo;outils redessin\u00e9e, le chat, la prise en charge de plusieurs moniteurs et l&rsquo;enregistrement de sessions en font un outil pr\u00e9cieux pour tous les utilisateurs au sein de votre organisation.  <\/p>\n<p>Notre derni\u00e8re version comprend \u00e9galement des fonctionnalit\u00e9s avanc\u00e9es que votre <a href=\"https:\/\/www.realvnc.com\/en\/blog\/helpdesk-in-realvnc-connect-v8\" target=\"_blank\" rel=\"noopener noreferrer\">service d&rsquo;assistance et vos \u00e9quipes informatiques<\/a> ne manqueront pas d&rsquo;appr\u00e9cier. RealVNC Connect Version 8 propose des codes de session auto-expirants qui expirent et sont remplac\u00e9s dans les deux minutes, ce qui garantit qu&rsquo;aucun code persistant ne peut \u00eatre utilis\u00e9 pour un acc\u00e8s non autoris\u00e9. En outre, cet outil vous permet de savoir qui se connecte, d&rsquo;avoir un acc\u00e8s sur invitation uniquement et de partager votre appareil avec <a href=\"https:\/\/www.realvnc.com\/en\/blog\/code-connect-realvnc-connect-v8-share-access-retain-control\/\" target=\"_blank\" rel=\"noopener noreferrer\">Code Connect<\/a>. Pr\u00eat \u00e0 vivre la nouvelle \u00e8re de l&rsquo;acc\u00e8s \u00e0 distance ? <a href=\"https:\/\/www.realvnc.com\/en\/connect\/download\" target=\"_blank\" rel=\"noopener noreferrer\">Essayez la derni\u00e8re version<\/a> de RealVNC Connect d\u00e8s aujourd&rsquo;hui !   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La br\u00e8ve histoire de la violation de donn\u00e9es GoTo\/LastPass GoTo a r\u00e9cemment annonc\u00e9 que, selon leur enqu\u00eate, \u00ab\u00a0un acteur de la menace a exfiltr\u00e9 des sauvegardes crypt\u00e9es d&rsquo;un service de stockage en nuage tiers li\u00e9 aux produits suivants : Central, Pro, join.me, Hamachi et RemotelyAnywhere\u00a0\u00bb. Paddy Srinivasan, PDG de GoTo, a soulign\u00e9 les efforts d\u00e9ploy\u00e9s &#8230; <a title=\"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance\" class=\"read-more\" href=\"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/\" aria-label=\"En savoir plus sur Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance\">Lire la suite<\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"template":"","blog_category":[],"class_list":["post-74167","blog","type-blog","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&#039;incident r\u00e9cent dit de l&#039;industrie des logiciels d&#039;acc\u00e8s \u00e0 distance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&#039;incident r\u00e9cent dit de l&#039;industrie des logiciels d&#039;acc\u00e8s \u00e0 distance\" \/>\n<meta property=\"og:description\" content=\"La br\u00e8ve histoire de la violation de donn\u00e9es GoTo\/LastPass GoTo a r\u00e9cemment annonc\u00e9 que, selon leur enqu\u00eate, \u00ab\u00a0un acteur de la menace a exfiltr\u00e9 des sauvegardes crypt\u00e9es d&rsquo;un service de stockage en nuage tiers li\u00e9 aux produits suivants : Central, Pro, join.me, Hamachi et RemotelyAnywhere\u00a0\u00bb. Paddy Srinivasan, PDG de GoTo, a soulign\u00e9 les efforts d\u00e9ploy\u00e9s ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/\" \/>\n<meta property=\"og:site_name\" content=\"RealVNC\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realvnc\" \/>\n<meta property=\"og:image\" content=\"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@realvnc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/\"},\"author\":{\"name\":\"Bogdan Bele\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#\\\/schema\\\/person\\\/6fa9f449ba19409f0cd7235931f51987\"},\"headline\":\"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance\",\"datePublished\":\"2025-09-03T15:51:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/\"},\"wordCount\":1405,\"publisher\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/\",\"name\":\"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l'incident r\u00e9cent dit de l'industrie des logiciels d'acc\u00e8s \u00e0 distance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\",\"datePublished\":\"2025-09-03T15:51:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\",\"contentUrl\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogs\",\"item\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/\",\"name\":\"RealVNC\u00ae\",\"description\":\"The world&#039;s safest remote access software\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#organization\",\"name\":\"RealVNC\u00ae\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/realvnc-logo-blue.png\",\"contentUrl\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/realvnc-logo-blue.png\",\"width\":300,\"height\":41,\"caption\":\"RealVNC\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realvnc\",\"https:\\\/\\\/x.com\\\/realvnc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/realvnc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/RealVNCLtd\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/RealVNC\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/fr\\\/#\\\/schema\\\/person\\\/6fa9f449ba19409f0cd7235931f51987\",\"name\":\"Bogdan Bele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g\",\"caption\":\"Bogdan Bele\"},\"description\":\"A journalist by formation and experience, and a content writer by trade. I\u2019ve been writing content, both online and offline, for more than 15 years. My focus has always been technology, but I\u2019ve also ventured into fields as diverse as music, football or news. I am RealVNC\u2019s in-house Digital Content Editor, so a lot of what you\u2019re reading on this blog is written by me. I also edit a lot of our content output. When I\u2019m not writing, editing or reading, you\u2019ll probably find me at a concert or watching a Chelsea FC game.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bogdanbele\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l'incident r\u00e9cent dit de l'industrie des logiciels d'acc\u00e8s \u00e0 distance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/","og_locale":"fr_FR","og_type":"article","og_title":"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l'incident r\u00e9cent dit de l'industrie des logiciels d'acc\u00e8s \u00e0 distance","og_description":"La br\u00e8ve histoire de la violation de donn\u00e9es GoTo\/LastPass GoTo a r\u00e9cemment annonc\u00e9 que, selon leur enqu\u00eate, \u00ab\u00a0un acteur de la menace a exfiltr\u00e9 des sauvegardes crypt\u00e9es d&rsquo;un service de stockage en nuage tiers li\u00e9 aux produits suivants : Central, Pro, join.me, Hamachi et RemotelyAnywhere\u00a0\u00bb. Paddy Srinivasan, PDG de GoTo, a soulign\u00e9 les efforts d\u00e9ploy\u00e9s ... Lire la suite","og_url":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/","og_site_name":"RealVNC\u00ae","article_publisher":"https:\/\/www.facebook.com\/realvnc","og_image":[{"url":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@realvnc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#article","isPartOf":{"@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/"},"author":{"name":"Bogdan Bele","@id":"https:\/\/www.realvnc.com\/fr\/#\/schema\/person\/6fa9f449ba19409f0cd7235931f51987"},"headline":"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance","datePublished":"2025-09-03T15:51:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/"},"wordCount":1405,"publisher":{"@id":"https:\/\/www.realvnc.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#primaryimage"},"thumbnailUrl":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/","url":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/","name":"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l'incident r\u00e9cent dit de l'industrie des logiciels d'acc\u00e8s \u00e0 distance","isPartOf":{"@id":"https:\/\/www.realvnc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#primaryimage"},"image":{"@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#primaryimage"},"thumbnailUrl":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","datePublished":"2025-09-03T15:51:44+00:00","breadcrumb":{"@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#primaryimage","url":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","contentUrl":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.realvnc.com\/fr\/blog\/violation-de-la-securite-de-goto-ce-que-lincident-recent-dit-de-lindustrie-des-logiciels-dacces-a-distance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.realvnc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blogs","item":"https:\/\/www.realvnc.com\/fr\/blog\/"},{"@type":"ListItem","position":3,"name":"Violation de la s\u00e9curit\u00e9 de Goto : Ce que l&rsquo;incident r\u00e9cent dit de l&rsquo;industrie des logiciels d&rsquo;acc\u00e8s \u00e0 distance"}]},{"@type":"WebSite","@id":"https:\/\/www.realvnc.com\/fr\/#website","url":"https:\/\/www.realvnc.com\/fr\/","name":"RealVNC\u00ae","description":"The world&#039;s safest remote access software","publisher":{"@id":"https:\/\/www.realvnc.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.realvnc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.realvnc.com\/fr\/#organization","name":"RealVNC\u00ae","url":"https:\/\/www.realvnc.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.realvnc.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/05\/realvnc-logo-blue.png","contentUrl":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/05\/realvnc-logo-blue.png","width":300,"height":41,"caption":"RealVNC\u00ae"},"image":{"@id":"https:\/\/www.realvnc.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realvnc","https:\/\/x.com\/realvnc","https:\/\/www.linkedin.com\/company\/realvnc\/","https:\/\/www.youtube.com\/RealVNCLtd","https:\/\/en.wikipedia.org\/wiki\/RealVNC"]},{"@type":"Person","@id":"https:\/\/www.realvnc.com\/fr\/#\/schema\/person\/6fa9f449ba19409f0cd7235931f51987","name":"Bogdan Bele","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g","caption":"Bogdan Bele"},"description":"A journalist by formation and experience, and a content writer by trade. I\u2019ve been writing content, both online and offline, for more than 15 years. My focus has always been technology, but I\u2019ve also ventured into fields as diverse as music, football or news. I am RealVNC\u2019s in-house Digital Content Editor, so a lot of what you\u2019re reading on this blog is written by me. I also edit a lot of our content output. When I\u2019m not writing, editing or reading, you\u2019ll probably find me at a concert or watching a Chelsea FC game.","sameAs":["https:\/\/www.linkedin.com\/in\/bogdanbele\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/blog\/74167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":0,"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/blog\/74167\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/media?parent=74167"}],"wp:term":[{"taxonomy":"blog_category","embeddable":true,"href":"https:\/\/www.realvnc.com\/fr\/wp-json\/wp\/v2\/blog_category?post=74167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}