{"id":104618,"date":"2026-05-25T10:23:02","date_gmt":"2026-05-25T09:23:02","guid":{"rendered":"https:\/\/www.realvnc.com\/connect\/customers\/reji\/"},"modified":"2026-06-19T06:31:04","modified_gmt":"2026-06-19T05:31:04","slug":"reji","status":"publish","type":"customer","link":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/","title":{"rendered":"REJI"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"104618\" class=\"elementor elementor-104618 elementor-30955\" data-elementor-post-type=\"customer\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50b211a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50b211a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0519207\" data-id=\"0519207\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef7fdd7 elementor-widget elementor-widget-heading\" data-id=\"ef7fdd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REJI \u00fcberwacht die Kiosk- und POS-Software der Kunden proaktiv mit RealVNC Connect<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb072c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb072c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ec94e9f\" data-id=\"ec94e9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1aff59 elementor-widget elementor-widget-spacer\" data-id=\"c1aff59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ef83be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ef83be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38ed34a\" data-id=\"38ed34a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f60ccf4 elementor-widget elementor-widget-spacer\" data-id=\"f60ccf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab6da41 elementor-widget elementor-widget-heading\" data-id=\"ab6da41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ver\u00e4nderungen in der Convenience-Industrie schaffen eine Chance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e703ede elementor-widget elementor-widget-heading\" data-id=\"e703ede\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><p>REJI bietet Software f\u00fcr Unternehmen in den Bereichen Quick Service Restaurant (QSR), Fast Casual und Convenience an, die von Anfang bis Ende auf das Kundenerlebnis ausgerichtet ist. Die REJI Viewport Software bietet den Benutzern nahtlose, integrierte L\u00f6sungen, die mit jedem bestehenden \u00d6kosystem kompatibel sind - von Selbstbestellungskiosken \u00fcber POS-Ger\u00e4te bis hin zum Self-Checkout. <\/p>\n<p>Sowohl die Kunden von REJI als auch das REJI-Supportteam \u00fcberwachen Ger\u00e4te, auf denen REJI Viewport l\u00e4uft, mit <a>RealVNC Connect<\/a>. Es erm\u00f6glicht eine schnellere und flexiblere \u00dcberwachung als konkurrierende Fernzugriffsl\u00f6sungen. Die Kompatibilit\u00e4t <a href=\"https:\/\/www.realvnc.com\/de\/verbinden\/\">von RealVNC Connect <\/a>mit einer Vielzahl von Betriebssystemen erm\u00f6glicht es REJI Viewport au\u00dferdem, mit der bestehenden IT-Infrastruktur eines jeden Kunden zu arbeiten, was die Integration wesentlich schneller und einfacher macht. <\/p><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-126a1bd elementor-widget elementor-widget-text-editor\" data-id=\"126a1bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>REJI wurde 2010 als Anbieter von POS-Software gegr\u00fcndet und expandierte 2013 in den Bereich der Software f\u00fcr Selbstbestellungskioske.<\/p><p>In den letzten Jahren haben viele Convenience-Store-Betreiber Gastronomiek\u00fcchen in ihren bestehenden Gesch\u00e4ftsr\u00e4umen er\u00f6ffnet. Vielerorts hat der Verkauf von Lebensmitteln auf Bestellung den Verkauf von Alkohol und Tabak als gr\u00f6\u00dfte Einnahmequelle in den L\u00e4den verdr\u00e4ngt. W\u00e4hrend einige Einzelh\u00e4ndler Franchisesysteme f\u00fcr bekannte QSR-Marken in ihren Gesch\u00e4ften er\u00f6ffnen, bietet die Einf\u00fchrung einer QSR-Eigenmarke dem Einzelh\u00e4ndler mehr Kontrolle und h\u00f6here Margen.  <\/p><p>Als REJI-Gr\u00fcnder Bernard Espanola und CEO Frank Yoder diesen Trend feststellten, erkannten sie eine Marktl\u00fccke. Damit Convenience Stores mit den etablierten QSRs konkurrieren k\u00f6nnen, m\u00fcssen sie ihren Kunden die qualitativ hochwertigen Kioske zur Selbstbestellung bieten, die sie heute erwarten. Dies ist jedoch ein ernsthaftes Hindernis f\u00fcr neue Marktteilnehmer in der Branche f\u00fcr frisch zubereitete Speisen auf Bestellung. Selbst gro\u00dfe multinationale Unternehmen tun sich manchmal schwer damit, eine Kioskflotte zu unterhalten, die einen hohen Standard an Kundenerlebnis bietet.   <\/p><p>Um diese L\u00fccke zu schlie\u00dfen, haben Bernard und Frank REJI Viewport entwickelt, ein System zur Unterst\u00fctzung und \u00dcberwachung digitaler Endpunkte, das auf die Wartung von gro\u00dfen Kiosk- und Digital Signage-Ger\u00e4ten spezialisiert ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f8209c elementor-widget elementor-widget-heading\" data-id=\"5f8209c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Das Problem<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5588f1 elementor-widget elementor-widget-heading\" data-id=\"c5588f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Um einen Kiosk oder eine Men\u00fcanzeige effektiv zu \u00fcberwachen, m\u00fcssen Sie den Bildschirm sehen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11df2b1 elementor-widget elementor-widget-text-editor\" data-id=\"11df2b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die wichtigsten Punkte f\u00fcr den Kundenkontakt in QSRs sind die Kiosk- und Men\u00fcbildschirme. Wenn diese ausfallen oder falsche Informationen anzeigen, ist das \u00e4rgerlich f\u00fcr die Restaurantbetreiber und untergr\u00e4bt das Kundenerlebnis. <\/p><p>Einzelh\u00e4ndler k\u00f6nnen generische \u00dcberwachungssysteme von der Stange f\u00fcr diese Ger\u00e4te einsetzen, aber diese Tools sind f\u00fcr diese Situation nicht geeignet. Diese L\u00f6sungen k\u00f6nnen nur \u00fcberwachen, wie stark die CPU eines Ger\u00e4ts ausgelastet war, wie viel Festplattenspeicher noch zur Verf\u00fcgung steht oder wann der Papiervorrat eines Bondruckers zur Neige geht. Sie k\u00f6nnen nicht erkennen, dass ein Fr\u00fchst\u00fccksmen\u00fc am Nachmittag angezeigt wird oder Restaurantbetreiber auf eine fehlgeschlagene Preisaktualisierung aufmerksam machen. Der einzige narrensichere Weg, um sicherzustellen, dass die Kunden das sehen, was sie sehen sollen, besteht darin, direkt zu \u00fcberwachen, was auf den Bildschirmen angezeigt wird.   <\/p><p>Hunderte von Kundenbildschirmen gleichzeitig im Auge zu behalten, ist eine gro\u00dfe logistische Herausforderung. Die \u00dcberpr\u00fcfung jedes einzelnen Bildschirms ist zeitaufw\u00e4ndig und unrealistisch f\u00fcr die \u00dcberwachung von Tausenden von Kiosken und digitalen Anzeigetafeln. Frank und Bernard erkannten, dass sie ein \u00dcberwachungstool brauchten, das mit der wachsenden Anzahl von Ger\u00e4ten, die die Selbstbedienungssoftware nutzen, skaliert werden konnte, und dass sie eine Fernzugriffsl\u00f6sung ben\u00f6tigen w\u00fcrden, die schnell und flexibel genug ist, um die Nachfrage zu bew\u00e4ltigen.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b9606 elementor-widget elementor-widget-heading\" data-id=\"e1b9606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entdeckung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3044c0 elementor-widget elementor-widget-heading\" data-id=\"f3044c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RealVNC Connect: Zugriff auf Hunderte von Fernverbindungen mit einem Klick<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2543fe6 elementor-widget elementor-widget-text-editor\" data-id=\"2543fe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die meisten Fernzugriffssoftware sind so konzipiert, dass sie jeweils nur auf ein Ger\u00e4t zugreifen k\u00f6nnen, was die \u00dcberwachung mehrerer kundenorientierter Kioske und Digital Signage-Bildschirme sehr umst\u00e4ndlich macht. Support-Mitarbeiter m\u00fcssen f\u00fcr jedes Ger\u00e4t ein Portal \u00f6ffnen und dieses Fenster dann sorgf\u00e4ltig im Verh\u00e4ltnis zu anderen offenen Portalfenstern (manchmal \u00fcber mehrere Monitore hinweg) positionieren und vergr\u00f6\u00dfern. <\/p><p>Das REJI-Entwicklungsteam hatte mit den ersten beiden Softwarel\u00f6sungen f\u00fcr den Fernzugriff, die sie implementierten, diese zeitraubenden Probleme. Beim dritten Versuch probierten sie <a href=\"https:\/\/www.realvnc.com\/de\/verbinden\/\">RealVNC Connect<\/a> aus und erkannten, dass sie die perfekte L\u00f6sung gefunden hatten. <\/p><p>Sobald die erste Fernzugriffsverbindung hergestellt ist, erm\u00f6glicht <a href=\"https:\/\/www.realvnc.com\/de\/verbinden\/\">RealVNC Connect<\/a> den Benutzern, eine .vnc-Dateierweiterung zu erstellen, die als Verkn\u00fcpfung f\u00fcr diese Verbindung dient. Jedes Mal, wenn die Datei ge\u00f6ffnet wird, nimmt das Fenster, das den Kiosk- oder Men\u00fcbildschirm anzeigt, die Gr\u00f6\u00dfe und Bildschirmposition der letzten Verwendung wieder an. Nachdem das REJI-Entwicklungsteam ein einfaches Skript erstellt hatte, konnte es Hunderte von Bildschirmansichten mit einem einzigen Klick \u00f6ffnen, und jede Ansicht wurde automatisch korrekt auf dem Bildschirm positioniert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03dd224 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03dd224\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-732f472\" data-id=\"732f472\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-76246c0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76246c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db8969b\" data-id=\"db8969b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-039b9b5 elementor-widget elementor-widget-image\" data-id=\"039b9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"434\" height=\"246\" src=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png\" class=\"attachment-large size-large wp-image-30958\" alt=\"\" srcset=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png 434w, https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study-300x170.png 300w\" sizes=\"(max-width: 434px) 100vw, 434px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-05079fb\" data-id=\"05079fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a63a574 elementor-widget elementor-widget-spacer\" data-id=\"a63a574\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28f8d11 elementor-widget elementor-widget-heading\" data-id=\"28f8d11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\"RealVNC Connect wurde zu unserer bevorzugten L\u00f6sung f\u00fcr den Fernzugriff, nachdem wir zwei andere bekannte Fernzugriffsl\u00f6sungen ausprobiert hatten. Diese anderen L\u00f6sungen boten zwar Fernzugriff, aber ihnen fehlte die Funktionalit\u00e4t, die wir brauchten, um Hunderte von Fernzugriffsverbindungen gleichzeitig visuell zu \u00fcberwachen. Mit RealVNC Connect kann REJI Viewport mit einem einzigen Mausklick Hunderte von Live-Monitoring-Portalen \u00f6ffnen.\"<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb96ccc elementor-widget elementor-widget-spacer\" data-id=\"eb96ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-537c4d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"537c4d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa91b3\" data-id=\"1aa91b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-590fc02 elementor-widget elementor-widget-spacer\" data-id=\"590fc02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abe73dd elementor-widget elementor-widget-heading\" data-id=\"abe73dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die L\u00f6sung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c04bd5 elementor-widget elementor-widget-heading\" data-id=\"5c04bd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RealVNC Connect unterst\u00fctzt die Integration der REJI Viewport Software in jedem bestehenden System<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fe748d elementor-widget elementor-widget-text-editor\" data-id=\"9fe748d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kurz nach der Umstellung entdeckte das REJI-Entwicklungsteam einen zweiten Vorteil von <a href=\"https:\/\/www.realvnc.com\/de\/verbinden\/\">RealVNC Connect<\/a>: die Kompatibilit\u00e4t mit einer besonders breiten Palette von Betriebssystemen.<\/p><p>REJI Viewport wurde entwickelt, um die Bildschirme von f\u00fcnf verschiedenen Komponenten, die im Einzelhandel verwendet werden, zu integrieren und anzuzeigen: den Selbstbestellungskiosk, den POS-Ger\u00e4te, die digitalen Men\u00fcanzeigen, das K\u00fcchendisplaysystem und die digitale Beschilderung im Gesch\u00e4ft.<\/p><p>Da es mit Windows, macOS, iOS, Android und Linux kompatibel ist, erm\u00f6glicht <a href=\"https:\/\/www.realvnc.com\/de\/verbinden\/\">RealVNC Connect<\/a> REJI die Arbeit mit einer Vielzahl von Ger\u00e4ten. So kann REJI seinen Kunden den Viewport-Service anbieten, ohne dass Ger\u00e4te ge\u00e4ndert werden m\u00fcssen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fc3d9a elementor-widget elementor-widget-heading\" data-id=\"9fc3d9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ergebnisse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f698e elementor-widget elementor-widget-heading\" data-id=\"25f698e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dank RealVNC Connect ist REJI bereit zu skalieren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-719b2ec elementor-widget elementor-widget-text-editor\" data-id=\"719b2ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit <a href=\"https:\/\/www.realvnc.com\/de\/verbinden\/\">RealVNC Connect<\/a> \u00f6ffnet das REJI-Supportteam jeden Morgen Hunderte von Kiosk- und Men\u00fcansichten auf einer Reihe von Monitoren in seinem Leitstand.<\/p><p>Wenn ein Kunde mit einem Kiosk interagiert, verschiebt Viewport das Fenster, das den aktiven Bildschirm anzeigt, automatisch auf den Hauptmonitor. Viewport vergr\u00f6\u00dfert dann sofort die Fenstergr\u00f6\u00dfe, so dass die Interaktion mit dem Kunden leichter in Echtzeit \u00fcberwacht werden kann. So kann sich das Support-Team auf die genutzten Bildschirme konzentrieren und darauf, wie die Kunden mit dem Kundenerlebnis interagieren.  <\/p><p>REJI setzt die Software bereits an Hunderten von Standorten in Texas, Alabama, Illinois, Florida und Mississippi ein und geht davon aus, dass die Nachfrage nach der REJI Viewport Software mit dem Anstieg der K\u00fcchener\u00f6ffnungen in Convenience Stores in ganz Amerika Schritt halten wird. Dank RealVNC Connect wird REJIs Supportleistung genauso schnell skalieren k\u00f6nnen wie die Nachfrage nach seiner Software. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e635c4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e635c4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b39881d\" data-id=\"b39881d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1de7a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1de7a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8585372\" data-id=\"8585372\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e8838 elementor-widget elementor-widget-image\" data-id=\"e5e8838\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"595\" height=\"460\" src=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji.png\" class=\"attachment-large size-large wp-image-30931\" alt=\"\" srcset=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji.png 595w, https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-300x232.png 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cc70a55\" data-id=\"cc70a55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54ac52f elementor-widget elementor-widget-spacer\" data-id=\"54ac52f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edce46e elementor-widget elementor-widget-heading\" data-id=\"edce46e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\"Die Tatsache, dass RealVNC Connect mit einer breiten Palette von Betriebssystemen kompatibel ist, ist wichtig f\u00fcr unser zuk\u00fcnftiges Wachstum. Wir stellen unseren Kunden Software zur Verf\u00fcgung, aber wir wollen auch First-Level-Support f\u00fcr ihr gesamtes \u00d6kosystem bieten. Mit RealVNC Connect k\u00f6nnen wir eine digitale Anzeigetafel \u00fcberwachen, die auf Android l\u00e4uft, oder Kundenkioske, die ein Windows-basiertes Betriebssystem haben. Die Flexibilit\u00e4t, mit jedem System arbeiten zu k\u00f6nnen, macht es f\u00fcr uns viel einfacher, jedem potenziellen Kunden 'Ja' zu sagen.\"<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f097b2 elementor-widget elementor-widget-spacer\" data-id=\"2f097b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a357e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a357e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f28ebe1\" data-id=\"f28ebe1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44aec33 elementor-widget elementor-widget-text-editor\" data-id=\"44aec33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tErfahren Sie mehr \u00fcber die RealVNC-Fernzugriffsintegration von REJI in unserem Podcast mit REJI-CEO Frank Yoder. Sie k\u00f6nnen ihn <a href=\"\/podcast\/\">hier bei einem Podcast-Anbieter Ihrer Wahl<\/a> anh\u00f6ren oder sich die Videoversion unten ansehen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-137b576 elementor-widget elementor-widget-video\" data-id=\"137b576\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=zruNVQhV0FE&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&#8222;Die Tatsache, dass RealVNC Connect mit einer breiten Palette von Betriebssystemen kompatibel ist, ist wichtig f\u00fcr unser zuk\u00fcnftiges Wachstum. Mit RealVNC Connect k\u00f6nnen wir eine digitale Anzeigetafel \u00fcberwachen, die auf Android l\u00e4uft, oder Kundenkioske, die ein Windows-basiertes Betriebssystem haben. Die Flexibilit\u00e4t, mit jedem System arbeiten zu k\u00f6nnen, macht es f\u00fcr uns viel einfacher, jedem potenziellen Kunden &#8218;Ja&#8216; zu sagen.&#8220;<\/p>\n<p>&#8211; Frank Yoder, CEO<\/p>\n","protected":false},"featured_media":0,"template":"","customer_category":[55],"class_list":["post-104618","customer","type-customer","status-publish","hentry","customer_category-retail-and-hospitality"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>REJI - RealVNC\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REJI\" \/>\n<meta property=\"og:description\" content=\"&quot;Die Tatsache, dass RealVNC Connect mit einer breiten Palette von Betriebssystemen kompatibel ist, ist wichtig f\u00fcr unser zuk\u00fcnftiges Wachstum. Mit RealVNC Connect k\u00f6nnen wir eine digitale Anzeigetafel \u00fcberwachen, die auf Android l\u00e4uft, oder Kundenkioske, die ein Windows-basiertes Betriebssystem haben. Die Flexibilit\u00e4t, mit jedem System arbeiten zu k\u00f6nnen, macht es f\u00fcr uns viel einfacher, jedem potenziellen Kunden &#039;Ja&#039; zu sagen.&quot; - Frank Yoder, CEO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/\" \/>\n<meta property=\"og:site_name\" content=\"RealVNC\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realvnc\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T05:31:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png\" \/>\n\t<meta property=\"og:image:width\" content=\"434\" \/>\n\t<meta property=\"og:image:height\" content=\"246\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@realvnc\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/\",\"name\":\"REJI - RealVNC\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/reji-case-study.png\",\"datePublished\":\"2026-05-25T09:23:02+00:00\",\"dateModified\":\"2026-06-19T05:31:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/reji-case-study.png\",\"contentUrl\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/reji-case-study.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/reji\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customers\",\"item\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/connect\\\/customers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"REJI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/\",\"name\":\"RealVNC\u00ae\",\"description\":\"The world&#039;s safest remote access software\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#organization\",\"name\":\"RealVNC\u00ae\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/realvnc-logo-blue.png\",\"contentUrl\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/realvnc-logo-blue.png\",\"width\":300,\"height\":41,\"caption\":\"RealVNC\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realvnc\",\"https:\\\/\\\/x.com\\\/realvnc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/realvnc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/RealVNCLtd\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/RealVNC\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"REJI - RealVNC\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/","og_locale":"de_DE","og_type":"article","og_title":"REJI","og_description":"\"Die Tatsache, dass RealVNC Connect mit einer breiten Palette von Betriebssystemen kompatibel ist, ist wichtig f\u00fcr unser zuk\u00fcnftiges Wachstum. Mit RealVNC Connect k\u00f6nnen wir eine digitale Anzeigetafel \u00fcberwachen, die auf Android l\u00e4uft, oder Kundenkioske, die ein Windows-basiertes Betriebssystem haben. Die Flexibilit\u00e4t, mit jedem System arbeiten zu k\u00f6nnen, macht es f\u00fcr uns viel einfacher, jedem potenziellen Kunden 'Ja' zu sagen.\" - Frank Yoder, CEO","og_url":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/","og_site_name":"RealVNC\u00ae","article_publisher":"https:\/\/www.facebook.com\/realvnc","article_modified_time":"2026-06-19T05:31:04+00:00","og_image":[{"width":434,"height":246,"url":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@realvnc","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/","url":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/","name":"REJI - RealVNC\u00ae","isPartOf":{"@id":"https:\/\/www.realvnc.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/#primaryimage"},"image":{"@id":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/#primaryimage"},"thumbnailUrl":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png","datePublished":"2026-05-25T09:23:02+00:00","dateModified":"2026-06-19T05:31:04+00:00","breadcrumb":{"@id":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/#primaryimage","url":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png","contentUrl":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/01\/reji-case-study.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.realvnc.com\/de\/connect\/customers\/reji\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.realvnc.com\/de\/"},{"@type":"ListItem","position":2,"name":"Customers","item":"https:\/\/www.realvnc.com\/de\/connect\/customers\/"},{"@type":"ListItem","position":3,"name":"REJI"}]},{"@type":"WebSite","@id":"https:\/\/www.realvnc.com\/de\/#website","url":"https:\/\/www.realvnc.com\/de\/","name":"RealVNC\u00ae","description":"The world&#039;s safest remote access software","publisher":{"@id":"https:\/\/www.realvnc.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.realvnc.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.realvnc.com\/de\/#organization","name":"RealVNC\u00ae","url":"https:\/\/www.realvnc.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.realvnc.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/05\/realvnc-logo-blue.png","contentUrl":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/05\/realvnc-logo-blue.png","width":300,"height":41,"caption":"RealVNC\u00ae"},"image":{"@id":"https:\/\/www.realvnc.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realvnc","https:\/\/x.com\/realvnc","https:\/\/www.linkedin.com\/company\/realvnc\/","https:\/\/www.youtube.com\/RealVNCLtd","https:\/\/en.wikipedia.org\/wiki\/RealVNC"]}]}},"_links":{"self":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/customer\/104618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/customer"}],"about":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/types\/customer"}],"version-history":[{"count":5,"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/customer\/104618\/revisions"}],"predecessor-version":[{"id":121324,"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/customer\/104618\/revisions\/121324"}],"wp:attachment":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/media?parent=104618"}],"wp:term":[{"taxonomy":"customer_category","embeddable":true,"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/customer_category?post=104618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}