{"id":70162,"date":"2025-07-17T11:26:50","date_gmt":"2025-07-17T11:26:50","guid":{"rendered":"https:\/\/www.realvnc.com\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/"},"modified":"2025-07-17T11:26:50","modified_gmt":"2025-07-17T11:26:50","slug":"goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt","status":"publish","type":"blog","link":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/","title":{"rendered":"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt"},"content":{"rendered":"<h2 data-pm-slice=\"1 1 []\">Die kurze Geschichte der GoTo\/LastPass-Datenverletzung<\/h2>\n<p>GoTo hat vor kurzem bekannt gegeben, dass laut ihrer Untersuchung &#8222;ein Bedrohungsakteur verschl\u00fcsselte Backups von einem Cloud-Speicherdienst eines Drittanbieters exfiltriert hat, der mit den folgenden Produkten in Verbindung steht: Central, Pro, join.me, Hamachi und RemotelyAnywhere.&#8220; Der CEO von GoTo, Paddy Srinivasan, betonte die Bem\u00fchungen des Unternehmens, die Kunden nach diesem Vorfall zu informieren und zu sch\u00fctzen. <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\"><\/p>\n<p>Ein Cyber-Bedrohungsakteur hat auch einen Verschl\u00fcsselungsschl\u00fcssel f\u00fcr ein Segment der verschl\u00fcsselten Backup-Daten extrahiert. Zu den betroffenen Informationen k\u00f6nnten &#8222;Kontonutzernamen, gesalzene und gehashte Passw\u00f6rter, ein Teil der Einstellungen f\u00fcr die Multifaktor-Authentifizierung (MFA) sowie einige Produkteinstellungen und Lizenzierungsinformationen&#8220; geh\u00f6ren. Nach diesem Sicherheitsversto\u00df bei GoTo wurden die Produkte des Unternehmens gr\u00fcndlich untersucht, um ihre Sicherheit und Funktionalit\u00e4t in dieser Zeit zu gew\u00e4hrleisten.  <\/p>\n<p>Die Produktionssysteme von GoTo waren nicht \u00fcber das hinaus betroffen, was zuvor bekannt gegeben wurde.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/24576493-ab98-462a-911d-32babadd011c.jpeg\"><\/p>\n<p>Das GoTo-eigene Unternehmen LastPass gab k\u00fcrzlich bekannt, dass ein Vorfall im August 2022 schwerwiegender war als bisher angenommen. Zu den betroffenen Daten geh\u00f6rten mit GoToMyPC verschl\u00fcsselte Datenbanken. Nachdem <a class=\"css-1rn59kg\" href=\"https:\/\/blog.lastpass.com\/2022\/12\/notice-of-recent-security-incident\/\" target=\"_blank\" rel=\"noopener noreferrer\">LastPass zun\u00e4chst behauptet hatte, es seien keine Kundendaten betroffen gewesen, r\u00e4umte das Unternehmen im Dezember ein, dass Kundendaten kompromittiert worden waren<\/a>. Der Unbefugte hatte sich Zugang zu einem Cloud-Speicherdienst eines Drittanbieters verschafft, in dem LastPass Daten speicherte, darunter Kontonutzernamen sowie gesalzene und gehashte Passw\u00f6rter. Die Daten der betroffenen Kunden k\u00f6nnen Benutzernamen und andere sensible Informationen enthalten.    <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cdn.pixabay.com\/photo\/2017\/02\/16\/08\/47\/castle-2070777_1280.jpg\" alt=\"\"><\/p>\n<p>Der Vorfall betraf auch die Einstellungen f\u00fcr die Multi-Faktor-Authentifizierung (MFA) einer kleinen Gruppe von Kunden, insbesondere im Zusammenhang mit den verschl\u00fcsselten Datenbanken von Rescue und GoToMyPC. GoTo hat daraufhin umfangreiche Ma\u00dfnahmen ergriffen, um die Passw\u00f6rter seiner Konten zu sch\u00fctzen und seine Sicherheitsma\u00dfnahmen insgesamt zu verbessern. Ein Teil dieser Ma\u00dfnahmen bestand darin, die betroffenen Kunden direkt zu kontaktieren, um ihnen zu versichern, dass die Backups verschl\u00fcsselt sind und die Authentifizierung robuster ist.  <\/p>\n<p>Nach mehreren Sicherheitsverletzungen in der Vergangenheit hat <a href=\"https:\/\/www.silicon.co.uk\/security\/cyberwar\/lastpass-separates-from-parent-after-security-incidents-561688\" target=\"_blank\" rel=\"noopener noreferrer\">sich LastPass im Mai 2024 offiziell von GoTo getrennt<\/a>, um sich st\u00e4rker auf die Cybersicherheit zu konzentrieren. Dies hat daf\u00fcr gesorgt, dass das Unternehmen die Daten seiner Kunden mit seiner verbesserten Identit\u00e4tsmanagement-Plattform sch\u00fctzt und sicherstellt, dass Passw\u00f6rter nie wieder geknackt werden. <\/p>\n<h2>Was sagt Ihnen die Sicherheitsverletzung bei GoTo \u00fcber die Datensicherheit?<\/h2>\n<p>Aus all dem l\u00e4sst sich nur eines mitnehmen: Wenn die Sicherheit nicht im Vordergrund steht, sind die betroffenen Benutzer diejenigen, die darunter leiden. Digitales Vertrauen und Datensicherheit sind f\u00fcr uns hier bei RealVNC sehr wichtig. Wir sind der Meinung, dass jeder Anbieter von <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/discover\/remote-access\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fernzugriff<\/a>, insbesondere ein Softwareanbieter, dies sehr ernst nehmen sollte. In der Realit\u00e4t ist es so, dass viele Unternehmen in Bezug auf zus\u00e4tzliche Sicherheit nicht das tun, was sie wollen. <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/importance-digital-trust-software-provider\/\" target=\"_blank\" rel=\"noopener noreferrer\">Digitales Vertrauen<\/a> und Datensicherheit sind f\u00fcr uns hier bei RealVNC sehr wichtig.   <\/p>\n<p>Bei der Entwicklung unseres Produkts steht die <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/connect\/security\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sicherheit an erster Stelle<\/a>, denn wir halten uns an unsere vier Sicherheitsprinzipien:<\/p>\n<ol>\n<li>Sie m\u00fcssen RealVNC als Unternehmen nicht vertrauen, um unserer Software und unseren Dienstleistungen zu vertrauen<\/li>\n<li>Wir zeichnen Ihre Sitzungen nicht auf, und die Daten k\u00f6nnen weder jetzt noch in Zukunft entschl\u00fcsselt werden.<\/li>\n<li>Jede Verbindung wird so behandelt, als ob sie in einer feindlichen Umgebung hergestellt w\u00fcrde<\/li>\n<li>Der Besitzer des Ferncomputers entscheidet letztendlich, wer eine Verbindung herstellen kann<\/li>\n<\/ol>\n<p>Jede einzelne Verbindung wird Ende-zu-Ende mit bis zu 256 Bit AES verschl\u00fcsselt. Wir verf\u00fcgen auch \u00fcber <a class=\"css-1rn59kg\" href=\"https:\/\/help.realvnc.com\/hc\/en-us\/articles\/360002250077\" target=\"_blank\" rel=\"noopener noreferrer\">2FA (Zwei-Faktor-Authentifizierung<\/a>) und empfehlen deren Verwendung dringend. <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2024\/03\/security-logos-circle.png\" alt=\"RealVNC-Logos f\u00fcr Sicherheit und Konformit\u00e4t\"><\/p>\n<h2>RealVNC Connect kann beweisen, dass es sicher ist<\/h2>\n<p>Wir behaupten nicht nur, dass wir sicher sind. Unsere <a href=\"https:\/\/www.realvnc.com\/en\/discover\/remote-desktop\/?lai_vid=OXgx5neBnClaw&amp;lai_sr=60-64&amp;lai_sl=h\" target=\"_blank\" rel=\"noopener noreferrer\">Fernzugriffsl\u00f6sung<\/a> ist die einzige, die von einem unabh\u00e4ngigen Sicherheitsexperten gepr\u00fcft und f\u00fcr sicher befunden wurde. Wir haben n\u00e4mlich unsere T\u00fcren f\u00fcr ein umfassendes <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/cure53-security-audit-reaffirms-realvnc-strong-security-stance\/\" target=\"_blank\" rel=\"noopener noreferrer\">White-Box-Sicherheitsaudit von Cure53<\/a> ge\u00f6ffnet. Dabei handelt es sich um eine weitaus gr\u00fcndlichere Sicherheits\u00fcberpr\u00fcfung als der traditionelle j\u00e4hrliche Penetrationstest, bei dem die Pr\u00fcfer vollen Zugriff auf unseren Quellcode, die interne API-Dokumentation und einen direkten Kommunikationsweg zu den Entwicklern erhalten. Wir sind sehr stolz auf die Ergebnisse, denn es wurden keine kritischen Probleme gefunden, was unsere starke Sicherheitseinstellung nur best\u00e4tigt. Wir werden weiterhin hart daran arbeiten, die gleichen hohen Sicherheitsstandards aufrechtzuerhalten.     <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/04\/unauthorized-access.jpg\"><\/p>\n<p>Wir freuen uns au\u00dferdem, Ihnen mitteilen zu k\u00f6nnen, dass die Android-Version von RealVNC Server for Mobile die <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/vnc-server-mobile-app-masa-validation\/\" target=\"_blank\" rel=\"noopener noreferrer\">erste Remote Access-App <\/a>ist, die den MASA-Prozess erfolgreich durchlaufen hat. Wir haben den Prozess f\u00fcr unsere RealVNC Mobile Server App im November 2022 in Zusammenarbeit mit der NCC Group, einem autorisierten MASA-Labor und einem wichtigen Akteur in der Sicherheitsbranche, durchgef\u00fchrt. Unsere Anwendung durchlief diese Pr\u00fcfung mit Bravour und erzielte ein hervorragendes Ergebnis: ein PASS in jedem Bereich beim ersten Durchlauf.  <\/p>\n<p>RealVNC wird auch weiterhin die gesamte Branche auffordern, den gleichen Weg zu gehen und zus\u00e4tzliche Sicherheit f\u00fcr ihre Produkte zu bieten. Wir haben dies auf den <a class=\"css-1rn59kg\" href=\"https:\/\/www.realvnc.com\/en\/blog\/came-for-ducks-stayed-for-talks-realvnc-infosecurity-europe-2022\/\" target=\"_blank\" rel=\"noopener noreferrer\">j\u00fcngsten Veranstaltungen zum Thema Cybersicherheit<\/a> getan und werden dies auch in Zukunft tun. <\/p>\n<blockquote><p>&#8222;<em>Wir bei RealVNC gehen davon aus, dass kein Unternehmen einem Anbieter glauben sollte, wenn er behauptet, dass seine Software sicher ist. Deshalb haben wir uns entschieden, ein White-Box-Audit mit einem hoch angesehenen Sicherheitsberatungsunternehmen durchzuf\u00fchren, um dies zu beweisen.&#8220;<\/em><\/p>\n<p>&#8211; Andrew Woodhouse, RealVNC Chief Information Officer<\/p><\/blockquote>\n<h2>Was sollten Sie als n\u00e4chstes tun?<\/h2>\n<p>Pr\u00fcfen Sie, ob Ihr Softwareanbieter (und insbesondere der Anbieter des Fernzugriffs) Ihnen einen Nachweis \u00fcber seine Sicherheit vorlegen kann. Und nehmen Sie ihn nicht einfach beim Wort! Verlangen Sie einen Nachweis in Form eines k\u00fcrzlich durchgef\u00fchrten unabh\u00e4ngigen Sicherheitsaudits. Wenn dies nicht m\u00f6glich ist, gibt es alternative Optionen, die Ihre Sicherheitsanforderungen erf\u00fcllen.   <\/p>\n<p>RealVNC Connect garantiert sicheren und zuverl\u00e4ssigen <a href=\"https:\/\/www.realvnc.com\/en\/connect\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fernzugriff<\/a> f\u00fcr alle. Es integriert sowohl den RealVNC Viewer als auch den RealVNC Server in eine einheitliche Desktop-Anwendung. Seine <a href=\"https:\/\/www.realvnc.com\/en\/blog\/realvnc-connect-v8-redesigned\/\" target=\"_blank\" rel=\"noopener noreferrer\">benutzerfreundliche Oberfl\u00e4che<\/a> und Funktionen wie Datei\u00fcbertragung, neu gestaltete Symbolleiste, Chat, Unterst\u00fctzung mehrerer Monitore und Sitzungsaufzeichnung machen es zu einem wertvollen Tool f\u00fcr alle Benutzer in Ihrem Unternehmen.  <\/p>\n<p>Unsere neueste Version enth\u00e4lt au\u00dferdem erweiterte Funktionen, die Ihre <a href=\"https:\/\/www.realvnc.com\/en\/blog\/helpdesk-in-realvnc-connect-v8\" target=\"_blank\" rel=\"noopener noreferrer\">Helpdesk- und IT-Teams<\/a> sicher zu sch\u00e4tzen wissen. RealVNC Connect Version 8 verf\u00fcgt \u00fcber selbst ablaufende Sitzungscodes, die innerhalb von zwei Minuten ablaufen und ersetzt werden, so dass sichergestellt ist, dass keine dauerhaften Codes f\u00fcr einen nicht autorisierten Zugriff verwendet werden k\u00f6nnen. Dar\u00fcber hinaus wissen Sie mit diesem Tool, wer sich einloggt, haben Zugriff nur f\u00fcr Eingeladene und k\u00f6nnen Ihr Ger\u00e4t mit <a href=\"https:\/\/www.realvnc.com\/en\/blog\/code-connect-realvnc-connect-v8-share-access-retain-control\/\" target=\"_blank\" rel=\"noopener noreferrer\">Code Connect<\/a> freigeben. Sind Sie bereit, die neue \u00c4ra des Fernzugriffs zu erleben? <a href=\"https:\/\/www.realvnc.com\/en\/connect\/download\" target=\"_blank\" rel=\"noopener noreferrer\">Testen Sie die neueste Version<\/a> von RealVNC Connect noch heute!   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die kurze Geschichte der GoTo\/LastPass-Datenverletzung GoTo hat vor kurzem bekannt gegeben, dass laut ihrer Untersuchung &#8222;ein Bedrohungsakteur verschl\u00fcsselte Backups von einem Cloud-Speicherdienst eines Drittanbieters exfiltriert hat, der mit den folgenden Produkten in Verbindung steht: Central, Pro, join.me, Hamachi und RemotelyAnywhere.&#8220; Der CEO von GoTo, Paddy Srinivasan, betonte die Bem\u00fchungen des Unternehmens, die Kunden nach diesem &#8230; <a title=\"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt\" class=\"read-more\" href=\"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/\" aria-label=\"Mehr Informationen \u00fcber Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt\">Weiterlesen<\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"template":"","blog_category":[],"class_list":["post-70162","blog","type-blog","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt\" \/>\n<meta property=\"og:description\" content=\"Die kurze Geschichte der GoTo\/LastPass-Datenverletzung GoTo hat vor kurzem bekannt gegeben, dass laut ihrer Untersuchung &#8222;ein Bedrohungsakteur verschl\u00fcsselte Backups von einem Cloud-Speicherdienst eines Drittanbieters exfiltriert hat, der mit den folgenden Produkten in Verbindung steht: Central, Pro, join.me, Hamachi und RemotelyAnywhere.&#8220; Der CEO von GoTo, Paddy Srinivasan, betonte die Bem\u00fchungen des Unternehmens, die Kunden nach diesem ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/\" \/>\n<meta property=\"og:site_name\" content=\"RealVNC\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realvnc\" \/>\n<meta property=\"og:image\" content=\"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@realvnc\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/\"},\"author\":{\"name\":\"Bogdan Bele\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#\\\/schema\\\/person\\\/6fa9f449ba19409f0cd7235931f51987\"},\"headline\":\"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt\",\"datePublished\":\"2025-07-17T11:26:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/\"},\"wordCount\":1107,\"publisher\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/\",\"name\":\"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\",\"datePublished\":\"2025-07-17T11:26:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\",\"contentUrl\":\"https:\\\/\\\/images.surferseo.art\\\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogs\",\"item\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/\",\"name\":\"RealVNC\u00ae\",\"description\":\"The world&#039;s safest remote access software\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#organization\",\"name\":\"RealVNC\u00ae\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/realvnc-logo-blue.png\",\"contentUrl\":\"https:\\\/\\\/www.realvnc.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/realvnc-logo-blue.png\",\"width\":300,\"height\":41,\"caption\":\"RealVNC\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realvnc\",\"https:\\\/\\\/x.com\\\/realvnc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/realvnc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/RealVNCLtd\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/RealVNC\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.realvnc.com\\\/de\\\/#\\\/schema\\\/person\\\/6fa9f449ba19409f0cd7235931f51987\",\"name\":\"Bogdan Bele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g\",\"caption\":\"Bogdan Bele\"},\"description\":\"A journalist by formation and experience, and a content writer by trade. I\u2019ve been writing content, both online and offline, for more than 15 years. My focus has always been technology, but I\u2019ve also ventured into fields as diverse as music, football or news. I am RealVNC\u2019s in-house Digital Content Editor, so a lot of what you\u2019re reading on this blog is written by me. I also edit a lot of our content output. When I\u2019m not writing, editing or reading, you\u2019ll probably find me at a concert or watching a Chelsea FC game.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bogdanbele\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/","og_locale":"de_DE","og_type":"article","og_title":"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt","og_description":"Die kurze Geschichte der GoTo\/LastPass-Datenverletzung GoTo hat vor kurzem bekannt gegeben, dass laut ihrer Untersuchung &#8222;ein Bedrohungsakteur verschl\u00fcsselte Backups von einem Cloud-Speicherdienst eines Drittanbieters exfiltriert hat, der mit den folgenden Produkten in Verbindung steht: Central, Pro, join.me, Hamachi und RemotelyAnywhere.&#8220; Der CEO von GoTo, Paddy Srinivasan, betonte die Bem\u00fchungen des Unternehmens, die Kunden nach diesem ... Weiterlesen","og_url":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/","og_site_name":"RealVNC\u00ae","article_publisher":"https:\/\/www.facebook.com\/realvnc","og_image":[{"url":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@realvnc","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#article","isPartOf":{"@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/"},"author":{"name":"Bogdan Bele","@id":"https:\/\/www.realvnc.com\/de\/#\/schema\/person\/6fa9f449ba19409f0cd7235931f51987"},"headline":"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt","datePublished":"2025-07-17T11:26:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/"},"wordCount":1107,"publisher":{"@id":"https:\/\/www.realvnc.com\/de\/#organization"},"image":{"@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#primaryimage"},"thumbnailUrl":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/","url":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/","name":"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt","isPartOf":{"@id":"https:\/\/www.realvnc.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#primaryimage"},"image":{"@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#primaryimage"},"thumbnailUrl":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","datePublished":"2025-07-17T11:26:50+00:00","breadcrumb":{"@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#primaryimage","url":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg","contentUrl":"https:\/\/images.surferseo.art\/89cd393c-6f8c-47e5-bea9-b8e36c2381a2.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.realvnc.com\/de\/blog\/goto-sicherheitsluecke-was-der-juengste-vorfall-ueber-die-branche-der-remote-access-software-aussagt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.realvnc.com\/de\/"},{"@type":"ListItem","position":2,"name":"Blogs","item":"https:\/\/www.realvnc.com\/de\/blog\/"},{"@type":"ListItem","position":3,"name":"Goto Sicherheitsl\u00fccke: Was der j\u00fcngste Vorfall \u00fcber die Branche der Remote Access Software aussagt"}]},{"@type":"WebSite","@id":"https:\/\/www.realvnc.com\/de\/#website","url":"https:\/\/www.realvnc.com\/de\/","name":"RealVNC\u00ae","description":"The world&#039;s safest remote access software","publisher":{"@id":"https:\/\/www.realvnc.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.realvnc.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.realvnc.com\/de\/#organization","name":"RealVNC\u00ae","url":"https:\/\/www.realvnc.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.realvnc.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/05\/realvnc-logo-blue.png","contentUrl":"https:\/\/www.realvnc.com\/wp-content\/uploads\/2023\/05\/realvnc-logo-blue.png","width":300,"height":41,"caption":"RealVNC\u00ae"},"image":{"@id":"https:\/\/www.realvnc.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realvnc","https:\/\/x.com\/realvnc","https:\/\/www.linkedin.com\/company\/realvnc\/","https:\/\/www.youtube.com\/RealVNCLtd","https:\/\/en.wikipedia.org\/wiki\/RealVNC"]},{"@type":"Person","@id":"https:\/\/www.realvnc.com\/de\/#\/schema\/person\/6fa9f449ba19409f0cd7235931f51987","name":"Bogdan Bele","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db953d23953822fd0e4cf9ec4b44b151a5712b3d00982d581e2c162042f75c3d?s=96&d=mm&r=g","caption":"Bogdan Bele"},"description":"A journalist by formation and experience, and a content writer by trade. I\u2019ve been writing content, both online and offline, for more than 15 years. My focus has always been technology, but I\u2019ve also ventured into fields as diverse as music, football or news. I am RealVNC\u2019s in-house Digital Content Editor, so a lot of what you\u2019re reading on this blog is written by me. I also edit a lot of our content output. When I\u2019m not writing, editing or reading, you\u2019ll probably find me at a concert or watching a Chelsea FC game.","sameAs":["https:\/\/www.linkedin.com\/in\/bogdanbele\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/blog\/70162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":0,"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/blog\/70162\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/media?parent=70162"}],"wp:term":[{"taxonomy":"blog_category","embeddable":true,"href":"https:\/\/www.realvnc.com\/de\/wp-json\/wp\/v2\/blog_category?post=70162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}